{"id":260,"count":15,"description":"","link":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/","name":"Fitness","slug":"fitness","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fitness Archives &#8226; Soft Sensibilities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fitness Archives &#8226; Soft Sensibilities\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/\" \/>\n<meta property=\"og:site_name\" content=\"Soft Sensibilities\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@abitcoquettish\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/tag\\\/fitness\\\/\",\"url\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/tag\\\/fitness\\\/\",\"name\":\"Fitness Archives &#8226; Soft Sensibilities\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/tag\\\/fitness\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/tag\\\/fitness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fitness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/\",\"name\":\"Soft Sensibilities\",\"description\":\"Now sensible, but a bit coquettish once upon a time.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kimberlypearl.co\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fitness Archives &#8226; Soft Sensibilities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/","og_locale":"en_US","og_type":"article","og_title":"Fitness Archives &#8226; Soft Sensibilities","og_url":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/","og_site_name":"Soft Sensibilities","twitter_card":"summary_large_image","twitter_site":"@abitcoquettish","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/","url":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/","name":"Fitness Archives &#8226; Soft Sensibilities","isPartOf":{"@id":"https:\/\/kimberlypearl.co\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kimberlypearl.co\/blog\/tag\/fitness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kimberlypearl.co\/blog\/"},{"@type":"ListItem","position":2,"name":"Fitness"}]},{"@type":"WebSite","@id":"https:\/\/kimberlypearl.co\/blog\/#website","url":"https:\/\/kimberlypearl.co\/blog\/","name":"Soft Sensibilities","description":"Now sensible, but a bit coquettish once upon a time.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimberlypearl.co\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kimberlypearl.co\/blog\/wp-json\/wp\/v2\/tags\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kimberlypearl.co\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kimberlypearl.co\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kimberlypearl.co\/blog\/wp-json\/wp\/v2\/posts?tags=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}